{"id":567,"date":"2025-04-03T15:07:53","date_gmt":"2025-04-03T15:07:53","guid":{"rendered":"https:\/\/arizona.stage.legacytraditional.org\/phoenix\/?page_id=567"},"modified":"2025-10-31T13:16:49","modified_gmt":"2025-10-31T20:16:49","slug":"contact","status":"publish","type":"page","link":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"margin-top:var(--wp--preset--spacing--16);margin-bottom:var(--wp--preset--spacing--16);padding-top:var(--wp--preset--spacing--16);padding-bottom:var(--wp--preset--spacing--64)\">\n<h2 class=\"wp-block-heading is-style-divider-top-center\" id=\"h-contact-us\">Contact us<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Whether you&#8217;re looking to connect with our District Office, a Legacy campus, a Media and Communications representative, or Vendor and Club Coordinators, we&#8217;re here to help. Find the right contact information below to get started.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull is-style-background-logo-small has-global-padding is-layout-constrained wp-container-core-group-is-layout-acadae8c wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--110);padding-bottom:var(--wp--preset--spacing--110)\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading is-style-divider-bottom-medium has-heading-3-font-size\" id=\"h-get-in-touch\" style=\"font-style:normal;font-weight:500\">Get in touch<\/h2>\n\n\n\n<p>We\u2019re serious when we say that we want to partner with you in your child\u2019s education.&nbsp; If you would like to discuss anything with us, please use the information below or fill out this form and we\u2019ll be in touch.<\/p>\n\n\n\n<p><strong>Contact your school directly if you need to speak to your child\u2019s school office to report absences and other campus-specific requests.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/Arizona.stage.legacytraditional.org\/find-your-school\/\" target=\"_blank\" rel=\"noreferrer noopener\">Find your school<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_5' ><form method='post' enctype='multipart\/form-data'  id='gform_5'  action='\/glendale\/wp-json\/wp\/v2\/pages\/567' data-formid='5' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_5' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_5_3\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_3'>First Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_3' id='input_5_3' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_5_4\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_4'>Last Name<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_4' id='input_5_4' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_5_5\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_5'>Email<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_5' id='input_5_5' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_5_6\" class=\"gfield gfield--type-phone gfield--input-type-phone gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_6'>Phone number<\/label><div class='ginput_container ginput_container_phone'><input name='input_6' id='input_5_6' type='tel' value='' class='large'    aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_5_10\" class=\"gfield gfield--type-textarea gfield--input-type-textarea gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_10'>Comments<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_10' id='input_5_10' class='textarea medium'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><div id=\"field_5_11\" class=\"gfield gfield--type-captcha gfield--input-type-captcha gfield--width-full field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_5_11'>CAPTCHA<\/label><div id='input_5_11' class='ginput_container ginput_recaptcha' data-sitekey='6LfyubgZAAAAADupkbSCXA-9gomditzbGg5AYiOG'  data-theme='light' data-tabindex='-1' data-size='invisible' data-badge='bottomright'><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_5' class=\"gform_button button wp-element-button\" onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Submit'  \/> \n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_5' value='postback' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_5' id='gform_theme_5' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_5' id='gform_style_settings_5' value='{&quot;theme&quot;:&quot;gravity-theme&quot;,&quot;inputPrimaryColor&quot;:&quot;#204ce5&quot;}' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_5' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='5' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_5' value='WyJbXSIsIjNmOTVmYmRlY2NmMWU2M2ZiZjk5NjMzNWY2NTNjMWQ4Il0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_5' id='gform_target_page_number_5' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_5' id='gform_source_page_number_5' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 5, 'https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_5').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_5');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_5').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_5').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_5').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_5').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/  }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_5').val();gformInitSpinner( 5, 'https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [5, current_page]);window['gf_submitting_5'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_5').replaceWith(confirmation_content);jQuery(document).trigger('gform_confirmation_loaded', [5]);window['gf_submitting_5'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_5').text());}else{jQuery('#gform_5').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"5\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_5\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_5\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_5\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 5, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-container-core-group-is-layout-ad319cd6 wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--80);padding-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<figure class=\"wp-block-image alignleft size-full\" style=\"margin-top:var(--wp--preset--spacing--64);margin-bottom:var(--wp--preset--spacing--64)\"><img decoding=\"async\" src=\"https:\/\/stage.legacytraditional.org\/wp-content\/uploads\/2025\/01\/contact-page-image.png\" alt=\"\" class=\"wp-image-2572\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-heading-5-font-size\" id=\"h-campus-address\">Campus address<\/h2>\n\n\n\n<p><strong>Legacy Glendale<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">13901 North 67th Ave., Glendale, AZ 85306<\/p>\n\n\n\n<p class=\"is-style-arrow-link has-medium-font-size\"><a href=\"#\">Get Directions<\/a><br><br><strong>Campus hours:<\/strong> 7:30 am \u2013 4 pm<\/p>\n\n\n\n<h2 class=\"wp-block-heading is-style-arrow-link-out is-style-divider-top has-heading-5-font-size\" id=\"h-contact-information\">Contact Information<\/h2>\n\n\n\n<p class=\"has-medium-font-size\"><strong>Principal:<\/strong> Roxanne Morris<br><strong>General questions:<\/strong> 623-219-4300<br><strong>Enrollment:<\/strong> 623-219-4300, option 1<br><strong>Community Education:<\/strong> 623-219-4300<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignwide has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--80);padding-bottom:var(--wp--preset--spacing--80)\">\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-stretch has-cream-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--48);padding-right:var(--wp--preset--spacing--48);padding-bottom:var(--wp--preset--spacing--48);padding-left:var(--wp--preset--spacing--48)\">\n<h2 class=\"wp-block-heading is-style-default has-heading-5-font-size\" id=\"h-media-amp-press\" style=\"font-style:normal;font-weight:500\">Media &amp; Press<\/h2>\n\n\n\n<p>Legacy Traditional Schools is dedicated to providing a top-quality education to students and families. We also want to answer your questions or help you with any stories you may be featuring. For more information specific to media and press relations, please email <a href=\"mailto:communications@legacytradtional.org\">communications@legacytradtional.org<\/a>.<br><br>If you are requesting access to Legacy Traditional Schools\u2019 public records, please submit a request using the Public Records Request Form.<\/p>\n\n\n\n<p class=\"is-style-arrow-link\"><a href=\"https:\/\/stage.legacytraditional.org\/public-records-request\/\" target=\"_blank\" rel=\"noreferrer noopener\">Public Records Request Form<\/a><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-stretch has-cream-background-color has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:var(--wp--preset--spacing--48);padding-right:var(--wp--preset--spacing--48);padding-bottom:var(--wp--preset--spacing--48);padding-left:var(--wp--preset--spacing--48)\">\n<h2 class=\"wp-block-heading is-style-default has-heading-5-font-size\" id=\"h-vendors-amp-clubs\" style=\"font-style:normal;font-weight:500\">Vendors &amp; Clubs<\/h2>\n\n\n\n<p>Legacy Traditional Schools welcomes partnerships with for-profit and non-profit organizations that offer enriching programs, activities, and services for our students.<\/p>\n\n\n\n<p>If you are interested in becoming an approved vendor or club partner, please contact the campus front office.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Contact us Whether you&#8217;re looking to connect with our District Office, a Legacy campus, a Media and Communications representative, or Vendor and Club Coordinators, we&#8217;re here to help. Find the right contact information below to get started. Get in touch We\u2019re serious when we say that we want to partner with you in your child\u2019s [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"single-lts_student_story","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-567","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v26.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact - Glendale | Legacy Traditional School<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact\" \/>\n<meta property=\"og:description\" content=\"Contact us Whether you&#8217;re looking to connect with our District Office, a Legacy campus, a Media and Communications representative, or Vendor and Club Coordinators, we&#8217;re here to help. Find the right contact information below to get started. Get in touch We\u2019re serious when we say that we want to partner with you in your child\u2019s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Glendale | Legacy Traditional School\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T20:16:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stage.legacytraditional.org\/wp-content\/uploads\/2025\/01\/contact-page-image.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/\",\"url\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/\",\"name\":\"Contact - Glendale | Legacy Traditional School\",\"isPartOf\":{\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/stage.legacytraditional.org\/wp-content\/uploads\/2025\/01\/contact-page-image.png\",\"datePublished\":\"2025-04-03T15:07:53+00:00\",\"dateModified\":\"2025-10-31T20:16:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/#primaryimage\",\"url\":\"https:\/\/stage.legacytraditional.org\/wp-content\/uploads\/2025\/01\/contact-page-image.png\",\"contentUrl\":\"https:\/\/stage.legacytraditional.org\/wp-content\/uploads\/2025\/01\/contact-page-image.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#website\",\"url\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/\",\"name\":\"Glendale | Legacy Traditional School\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#organization\",\"name\":\"Glendale | Legacy Traditional School\",\"url\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-content\/uploads\/sites\/6\/sites\/38\/2025\/04\/logo.svg\",\"contentUrl\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-content\/uploads\/sites\/6\/sites\/38\/2025\/04\/logo.svg\",\"width\":240,\"height\":76,\"caption\":\"Glendale | Legacy Traditional School\"},\"image\":{\"@id\":\"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Contact - Glendale | Legacy Traditional School","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"Contact","og_description":"Contact us Whether you&#8217;re looking to connect with our District Office, a Legacy campus, a Media and Communications representative, or Vendor and Club Coordinators, we&#8217;re here to help. Find the right contact information below to get started. Get in touch We\u2019re serious when we say that we want to partner with you in your child\u2019s [&hellip;]","og_url":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/","og_site_name":"Glendale | Legacy Traditional School","article_modified_time":"2025-10-31T20:16:49+00:00","og_image":[{"url":"https:\/\/stage.legacytraditional.org\/wp-content\/uploads\/2025\/01\/contact-page-image.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/","url":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/","name":"Contact - Glendale | Legacy Traditional School","isPartOf":{"@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/#primaryimage"},"image":{"@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/#primaryimage"},"thumbnailUrl":"https:\/\/stage.legacytraditional.org\/wp-content\/uploads\/2025\/01\/contact-page-image.png","datePublished":"2025-04-03T15:07:53+00:00","dateModified":"2025-10-31T20:16:49+00:00","breadcrumb":{"@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/#primaryimage","url":"https:\/\/stage.legacytraditional.org\/wp-content\/uploads\/2025\/01\/contact-page-image.png","contentUrl":"https:\/\/stage.legacytraditional.org\/wp-content\/uploads\/2025\/01\/contact-page-image.png"},{"@type":"BreadcrumbList","@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#website","url":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/","name":"Glendale | Legacy Traditional School","description":"","publisher":{"@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#organization","name":"Glendale | Legacy Traditional School","url":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#\/schema\/logo\/image\/","url":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-content\/uploads\/sites\/6\/sites\/38\/2025\/04\/logo.svg","contentUrl":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-content\/uploads\/sites\/6\/sites\/38\/2025\/04\/logo.svg","width":240,"height":76,"caption":"Glendale | Legacy Traditional School"},"image":{"@id":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-json\/wp\/v2\/pages\/567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-json\/wp\/v2\/comments?post=567"}],"version-history":[{"count":5,"href":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-json\/wp\/v2\/pages\/567\/revisions"}],"predecessor-version":[{"id":1133,"href":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-json\/wp\/v2\/pages\/567\/revisions\/1133"}],"wp:attachment":[{"href":"https:\/\/arizona.stage.legacytraditional.org\/glendale\/wp-json\/wp\/v2\/media?parent=567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}